{"id":197,"date":"2022-11-15T22:40:22","date_gmt":"2022-11-15T20:40:22","guid":{"rendered":"https:\/\/etnabrasyl.com\/?page_id=197"},"modified":"2022-11-16T14:13:56","modified_gmt":"2022-11-16T12:13:56","slug":"mentions-legales","status":"publish","type":"page","link":"https:\/\/etnabrasyl.com\/index.php\/mentions-legales\/","title":{"rendered":"Mentions l\u00e9gales"},"content":{"rendered":"\n<h2 class=\"has-medium-font-size wp-block-heading\">1 \u2013 \u00c9dition du site<\/h2>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">En vertu de <a href=\"https:\/\/www.legifrance.gouv.fr\/affichTexte.do?cidTexte=JORFTEXT000000801164#LEGIARTI000042038977\" target=\"_blank\" rel=\"noreferrer noopener\">l\u2019article 6 de la loi n\u00b0 2004-575 du 21 juin 2004<\/a> pour la confiance dans l\u2019\u00e9conomie num\u00e9rique, il est pr\u00e9cis\u00e9 aux utilisateurs du site internet <strong>https:\/\/etnabrasyl.com<\/strong> l\u2019identit\u00e9 des diff\u00e9rents intervenants dans le cadre de sa r\u00e9alisation et de son suivi:<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><strong>Propri\u00e9taire du site : <\/strong>Etna Brasyl  \u2013 Contact : ebrasyl@gmail.com &#8211; Tel :  +33 618061584. \u2013 Adresse : 77320 SAINT MARS VIEUX MAISONS.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><strong>Identification de l\u2019organisme :<\/strong> Artiste ind\u00e9pendant  \u2013 Adresse postale : 77320 SAINT MARS VIEUX MAISONS.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><strong>Responsable de la publication : <\/strong>Etna Brasyl \u2013 Contact : +33 618061584.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><strong>H\u00e9bergeur :<\/strong> HOSTINGER INTERNATIONAL LTD, sis 61 Lordou Vironos Street, 6023 Larnaca, Chypre<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><strong>D\u00e9l\u00e9gu\u00e9 \u00e0 la protection des donn\u00e9es : <\/strong>Etna Brasyl \u2013 ebrasyl@gmail.com<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-default\"\/>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">2 \u2013 Propri\u00e9t\u00e9 intellectuelle et contrefa\u00e7ons.<\/h2>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><strong>Etna Brasyl <\/strong>est propri\u00e9taire des droits de propri\u00e9t\u00e9 intellectuelle et d\u00e9tient les droits d\u2019usage sur tous les \u00e9l\u00e9ments accessibles sur le site internet, notamment les textes, images, graphismes, logos, vid\u00e9os, architecture, ic\u00f4nes et sons.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Toute reproduction, repr\u00e9sentation, modification, publication, adaptation de tout ou partie des \u00e9l\u00e9ments du site, quel que soit le moyen ou le proc\u00e9d\u00e9 utilis\u00e9, est interdite, sauf autorisation \u00e9crite pr\u00e9alable de <strong>Etna Brasyl<\/strong>.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Toute exploitation non autoris\u00e9e du site ou de l\u2019un quelconque des \u00e9l\u00e9ments qu\u2019il contient sera consid\u00e9r\u00e9e comme constitutive d\u2019une contrefa\u00e7on et poursuivie conform\u00e9ment aux dispositions des articles <a href=\"https:\/\/www.legifrance.gouv.fr\/affichCodeArticle.do?idArticle=LEGIARTI000032655082&amp;cidTexte=LEGITEXT000006069414&amp;dateTexte=20160605\" target=\"_blank\" rel=\"noreferrer noopener\">L.335-2 et suivants du Code de Propri\u00e9t\u00e9 Intellectuelle<\/a>.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">3 \u2013 Limitations de responsabilit\u00e9.<\/h2>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><strong>Etna Brasyl <\/strong> ne pourra \u00eatre tenu pour responsable des dommages directs et indirects caus\u00e9s au mat\u00e9riel de l\u2019utilisateur, lors de l\u2019acc\u00e8s au site <strong><strong><a href=\"https:\/\/etnabrasyl.com\">https:\/\/etnabrasyl.com<\/a><\/strong><\/strong>.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><strong>Etna Brasyl <\/strong> d\u00e9cline toute responsabilit\u00e9 quant \u00e0 l\u2019utilisation qui pourrait \u00eatre faite des informations et contenus pr\u00e9sents sur <a href=\"https:\/\/etnabrasyl.com\"><strong>https:\/\/etnabrasyl.com<\/strong><\/a>.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><strong><strong>Etna Brasyl <\/strong><\/strong> s\u2019engage \u00e0 s\u00e9curiser au mieux le site<a href=\"https:\/\/etnabrasyl.com\" title=\"\"> <strong><strong>https:\/\/etnabrasyl.com<\/strong><\/strong><\/a>, cependant sa responsabilit\u00e9 ne pourra \u00eatre mise en cause si des donn\u00e9es ind\u00e9sirables sont import\u00e9es et install\u00e9es sur son site \u00e0 son insu.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Des espaces interactifs (espace contact ou commentaires) sont \u00e0 la disposition des utilisateurs. Etna Brasyl<strong> <\/strong> se r\u00e9serve le droit de supprimer, sans mise en demeure pr\u00e9alable, tout contenu d\u00e9pos\u00e9 dans cet espace qui contreviendrait \u00e0 la l\u00e9gislation applicable en France, en particulier aux dispositions relatives \u00e0 la protection des donn\u00e9es.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Le cas \u00e9ch\u00e9ant, <strong>Etna Brasyl <\/strong>se r\u00e9serve \u00e9galement la possibilit\u00e9 de mettre en cause la responsabilit\u00e9 civile et\/ou p\u00e9nale de l\u2019utilisateur, notamment en cas de message \u00e0 caract\u00e8re raciste, injurieux, diffamant, ou pornographique, quel que soit le support utilis\u00e9 (texte, photographie \u2026).<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">4 \u2013 CNIL et gestion des donn\u00e9es personnelles.<\/h2>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Conform\u00e9ment aux dispositions de <a href=\"https:\/\/www.legifrance.gouv.fr\/affichTexte.do?cidTexte=JORFTEXT000000886460\" target=\"_blank\" rel=\"noreferrer noopener\">la loi 78-17 du 6 janvier 1978 modifi\u00e9e<\/a>, l\u2019utilisateur du site <a href=\"https:\/\/etnabrasyl.com\" title=\"\"><strong>https:\/\/etnabrasyl.com<\/strong><\/a> dispose d\u2019un droit d\u2019acc\u00e8s, de modification et de suppression des informations collect\u00e9es. Pour exercer ce droit, envoyez un message \u00e0 notre D\u00e9l\u00e9gu\u00e9 \u00e0 la Protection des Donn\u00e9es : <strong>Etna Brasyl<\/strong> \u2013 <strong>ebrasyl@gmail.com<\/strong>.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Pour plus d\u2019informations sur la fa\u00e7on dont nous traitons vos donn\u00e9es (type de donn\u00e9es, finalit\u00e9, destinataire\u2026), lisez notre politique de confidentialit\u00e9 : <strong><a href=\"https:\/\/etnabrasyl.com\/index.php\/politique-de-confidentialite\/\" title=\"\">https:\/\/etnabrasyl.com\/index.php\/politique-de-confidentialite<\/a>.<\/strong><\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">5 \u2013 Liens hypertextes et cookies<\/h2>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Le site <strong><strong><a href=\"https:\/\/etnabrasyl.com\"><strong>https:\/\/etnabrasyl.com<\/strong><\/a><\/strong><\/strong> contient des liens hypertextes vers d\u2019autres sites et d\u00e9gage toute responsabilit\u00e9 \u00e0 propos de ces liens externes ou des liens cr\u00e9\u00e9s par d\u2019autres sites vers <strong><a href=\"https:\/\/etnabrasyl.com\" title=\"\">https:\/\/etnabrasyl.com<\/a>.<\/strong><\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">La navigation sur le site <strong><a href=\"https:\/\/etnabrasyl.com\"><strong>https:\/\/etnabrasyl.com<\/strong><\/a><strong>\/<\/strong><\/strong> est susceptible de provoquer l\u2019installation de cookie(s) sur l\u2019ordinateur de l\u2019utilisateur.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Un \u201ccookie\u201d est un fichier de petite taille qui enregistre des informations relatives \u00e0 la navigation d\u2019un utilisateur sur un site. Les donn\u00e9es ainsi obtenues permettent d\u2019obtenir des mesures de fr\u00e9quentation, par exemple.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Vous avez la possibilit\u00e9 <strong>d\u2019accepter ou de refuser les cookies<\/strong> en modifiant les param\u00e8tres de votre navigateur. Aucun cookie ne sera d\u00e9pos\u00e9 sans votre consentement.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Les cookies sont enregistr\u00e9s pour une dur\u00e9e maximale de 13 mois.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Pour plus d\u2019informations sur la fa\u00e7on dont nous faisons usage des cookies, lisez notre <strong><a href=\"https:\/\/etnabrasyl.com\/index.php\/politique-de-confidentialite\/\" title=\"\">https:\/\/etnabrasyl.com\/index.php\/politique-de-confidentialite<\/a>.<\/strong><\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"has-medium-font-size wp-block-heading\">6 \u2013 Droit applicable et attribution de juridiction.<\/h2>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\">Tout litige en relation avec l\u2019utilisation du site <strong><a href=\"https:\/\/etnabrasyl.com\"><strong>https:\/\/etnabrasyl.com<\/strong><\/a><\/strong> est soumis au droit fran\u00e7ais. En dehors des cas o\u00f9 la loi ne le permet pas, il est fait attribution exclusive de juridiction aux tribunaux comp\u00e9tents de <strong>Tribunal Judiciaire de Meaux, sis 44, Avenue Salvador Allende BP 230 7710<\/strong><\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>1 \u2013 \u00c9dition du site En vertu de l\u2019article 6 de la loi n\u00b0 2004-575 du 21 juin 2004 pour la confiance dans l\u2019\u00e9conomie num\u00e9rique, il est pr\u00e9cis\u00e9 aux utilisateurs du site internet https:\/\/etnabrasyl.com l\u2019identit\u00e9 des diff\u00e9rents intervenants dans le cadre de sa r\u00e9alisation et de son suivi: Propri\u00e9taire du site : Etna Brasyl \u2013 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-197","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"1 \u2013 \u00c9dition du site En vertu de l\u2019article 6 de la loi n\u00b0 2004-575 du 21 juin 2004 pour la confiance dans l\u2019\u00e9conomie num\u00e9rique, il est pr\u00e9cis\u00e9 aux utilisateurs du site internet https:\/\/etnabrasyl.com l\u2019identit\u00e9 des diff\u00e9rents intervenants dans le cadre de sa r\u00e9alisation et de son suivi: Propri\u00e9taire du site : Etna Brasyl \u2013\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/etnabrasyl.com\/index.php\/mentions-legales\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Etna Brasyl - Le Br\u00e9sil \u00e0 port\u00e9e de voix\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Mentions l\u00e9gales - Etna Brasyl\" \/>\n\t\t<meta property=\"og:description\" content=\"1 \u2013 \u00c9dition du site En vertu de l\u2019article 6 de la loi n\u00b0 2004-575 du 21 juin 2004 pour la confiance dans l\u2019\u00e9conomie num\u00e9rique, il est pr\u00e9cis\u00e9 aux utilisateurs du site internet https:\/\/etnabrasyl.com l\u2019identit\u00e9 des diff\u00e9rents intervenants dans le cadre de sa r\u00e9alisation et de son suivi: Propri\u00e9taire du site : Etna Brasyl \u2013\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/etnabrasyl.com\/index.php\/mentions-legales\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/etnabrasyl.com\/wp-content\/uploads\/2022\/11\/cropped-banner.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/etnabrasyl.com\/wp-content\/uploads\/2022\/11\/cropped-banner.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-11-15T20:40:22+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-11-16T12:13:56+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Mentions l\u00e9gales - Etna Brasyl\" \/>\n\t\t<meta name=\"twitter:description\" content=\"1 \u2013 \u00c9dition du site En vertu de l\u2019article 6 de la loi n\u00b0 2004-575 du 21 juin 2004 pour la confiance dans l\u2019\u00e9conomie num\u00e9rique, il est pr\u00e9cis\u00e9 aux utilisateurs du site internet https:\/\/etnabrasyl.com l\u2019identit\u00e9 des diff\u00e9rents intervenants dans le cadre de sa r\u00e9alisation et de son suivi: Propri\u00e9taire du site : Etna Brasyl \u2013\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/etnabrasyl.com\/wp-content\/uploads\/2022\/11\/cropped-banner.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/etnabrasyl.com\\\/index.php\\\/mentions-legales\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/etnabrasyl.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/etnabrasyl.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/etnabrasyl.com\\\/index.php\\\/mentions-legales\\\/#listItem\",\"name\":\"Mentions l\\u00e9gales\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/etnabrasyl.com\\\/index.php\\\/mentions-legales\\\/#listItem\",\"position\":2,\"name\":\"Mentions l\\u00e9gales\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/etnabrasyl.com#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/etnabrasyl.com\\\/#organization\",\"name\":\"etnabrasyl\",\"description\":\"Le Br\\u00e9sil \\u00e0 port\\u00e9e de voix\",\"url\":\"https:\\\/\\\/etnabrasyl.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/etnabrasyl.com\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/cropped-banner.png\",\"@id\":\"https:\\\/\\\/etnabrasyl.com\\\/index.php\\\/mentions-legales\\\/#organizationLogo\",\"width\":1248,\"height\":100},\"image\":{\"@id\":\"https:\\\/\\\/etnabrasyl.com\\\/index.php\\\/mentions-legales\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/etnabrasyl.com\\\/index.php\\\/mentions-legales\\\/#webpage\",\"url\":\"https:\\\/\\\/etnabrasyl.com\\\/index.php\\\/mentions-legales\\\/\",\"name\":\"Mentions l\\u00e9gales - Etna Brasyl\",\"description\":\"1 \\u2013 \\u00c9dition du site En vertu de l\\u2019article 6 de la loi n\\u00b0 2004-575 du 21 juin 2004 pour la confiance dans l\\u2019\\u00e9conomie num\\u00e9rique, il est pr\\u00e9cis\\u00e9 aux utilisateurs du site internet https:\\\/\\\/etnabrasyl.com l\\u2019identit\\u00e9 des diff\\u00e9rents intervenants dans le cadre de sa r\\u00e9alisation et de son suivi: Propri\\u00e9taire du site : Etna Brasyl \\u2013\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/etnabrasyl.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/etnabrasyl.com\\\/index.php\\\/mentions-legales\\\/#breadcrumblist\"},\"datePublished\":\"2022-11-15T22:40:22+02:00\",\"dateModified\":\"2022-11-16T14:13:56+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/etnabrasyl.com\\\/#website\",\"url\":\"https:\\\/\\\/etnabrasyl.com\\\/\",\"name\":\"etnabrasyl\",\"description\":\"Le Br\\u00e9sil \\u00e0 port\\u00e9e de voix\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/etnabrasyl.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Mentions l\u00e9gales - Etna Brasyl","description":"1 \u2013 \u00c9dition du site En vertu de l\u2019article 6 de la loi n\u00b0 2004-575 du 21 juin 2004 pour la confiance dans l\u2019\u00e9conomie num\u00e9rique, il est pr\u00e9cis\u00e9 aux utilisateurs du site internet https:\/\/etnabrasyl.com l\u2019identit\u00e9 des diff\u00e9rents intervenants dans le cadre de sa r\u00e9alisation et de son suivi: Propri\u00e9taire du site : Etna Brasyl \u2013","canonical_url":"https:\/\/etnabrasyl.com\/index.php\/mentions-legales\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/etnabrasyl.com\/index.php\/mentions-legales\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/etnabrasyl.com#listItem","position":1,"name":"Home","item":"https:\/\/etnabrasyl.com","nextItem":{"@type":"ListItem","@id":"https:\/\/etnabrasyl.com\/index.php\/mentions-legales\/#listItem","name":"Mentions l\u00e9gales"}},{"@type":"ListItem","@id":"https:\/\/etnabrasyl.com\/index.php\/mentions-legales\/#listItem","position":2,"name":"Mentions l\u00e9gales","previousItem":{"@type":"ListItem","@id":"https:\/\/etnabrasyl.com#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/etnabrasyl.com\/#organization","name":"etnabrasyl","description":"Le Br\u00e9sil \u00e0 port\u00e9e de voix","url":"https:\/\/etnabrasyl.com\/","logo":{"@type":"ImageObject","url":"https:\/\/etnabrasyl.com\/wp-content\/uploads\/2022\/11\/cropped-banner.png","@id":"https:\/\/etnabrasyl.com\/index.php\/mentions-legales\/#organizationLogo","width":1248,"height":100},"image":{"@id":"https:\/\/etnabrasyl.com\/index.php\/mentions-legales\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/etnabrasyl.com\/index.php\/mentions-legales\/#webpage","url":"https:\/\/etnabrasyl.com\/index.php\/mentions-legales\/","name":"Mentions l\u00e9gales - Etna Brasyl","description":"1 \u2013 \u00c9dition du site En vertu de l\u2019article 6 de la loi n\u00b0 2004-575 du 21 juin 2004 pour la confiance dans l\u2019\u00e9conomie num\u00e9rique, il est pr\u00e9cis\u00e9 aux utilisateurs du site internet https:\/\/etnabrasyl.com l\u2019identit\u00e9 des diff\u00e9rents intervenants dans le cadre de sa r\u00e9alisation et de son suivi: Propri\u00e9taire du site : Etna Brasyl \u2013","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/etnabrasyl.com\/#website"},"breadcrumb":{"@id":"https:\/\/etnabrasyl.com\/index.php\/mentions-legales\/#breadcrumblist"},"datePublished":"2022-11-15T22:40:22+02:00","dateModified":"2022-11-16T14:13:56+02:00"},{"@type":"WebSite","@id":"https:\/\/etnabrasyl.com\/#website","url":"https:\/\/etnabrasyl.com\/","name":"etnabrasyl","description":"Le Br\u00e9sil \u00e0 port\u00e9e de voix","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/etnabrasyl.com\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Etna Brasyl - Le Br\u00e9sil \u00e0 port\u00e9e de voix","og:type":"article","og:title":"Mentions l\u00e9gales - Etna Brasyl","og:description":"1 \u2013 \u00c9dition du site En vertu de l\u2019article 6 de la loi n\u00b0 2004-575 du 21 juin 2004 pour la confiance dans l\u2019\u00e9conomie num\u00e9rique, il est pr\u00e9cis\u00e9 aux utilisateurs du site internet https:\/\/etnabrasyl.com l\u2019identit\u00e9 des diff\u00e9rents intervenants dans le cadre de sa r\u00e9alisation et de son suivi: Propri\u00e9taire du site : Etna Brasyl \u2013","og:url":"https:\/\/etnabrasyl.com\/index.php\/mentions-legales\/","og:image":"https:\/\/etnabrasyl.com\/wp-content\/uploads\/2022\/11\/cropped-banner.png","og:image:secure_url":"https:\/\/etnabrasyl.com\/wp-content\/uploads\/2022\/11\/cropped-banner.png","article:published_time":"2022-11-15T20:40:22+00:00","article:modified_time":"2022-11-16T12:13:56+00:00","twitter:card":"summary_large_image","twitter:title":"Mentions l\u00e9gales - Etna Brasyl","twitter:description":"1 \u2013 \u00c9dition du site En vertu de l\u2019article 6 de la loi n\u00b0 2004-575 du 21 juin 2004 pour la confiance dans l\u2019\u00e9conomie num\u00e9rique, il est pr\u00e9cis\u00e9 aux utilisateurs du site internet https:\/\/etnabrasyl.com l\u2019identit\u00e9 des diff\u00e9rents intervenants dans le cadre de sa r\u00e9alisation et de son suivi: Propri\u00e9taire du site : Etna Brasyl \u2013","twitter:image":"https:\/\/etnabrasyl.com\/wp-content\/uploads\/2022\/11\/cropped-banner.png"},"aioseo_meta_data":{"post_id":"197","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-11-15 20:32:51","updated":"2025-06-04 10:21:07","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/etnabrasyl.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMentions l\u00e9gales\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/etnabrasyl.com"},{"label":"Mentions l\u00e9gales","link":"https:\/\/etnabrasyl.com\/index.php\/mentions-legales\/"}],"_links":{"self":[{"href":"https:\/\/etnabrasyl.com\/index.php\/wp-json\/wp\/v2\/pages\/197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/etnabrasyl.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/etnabrasyl.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/etnabrasyl.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/etnabrasyl.com\/index.php\/wp-json\/wp\/v2\/comments?post=197"}],"version-history":[{"count":4,"href":"https:\/\/etnabrasyl.com\/index.php\/wp-json\/wp\/v2\/pages\/197\/revisions"}],"predecessor-version":[{"id":269,"href":"https:\/\/etnabrasyl.com\/index.php\/wp-json\/wp\/v2\/pages\/197\/revisions\/269"}],"wp:attachment":[{"href":"https:\/\/etnabrasyl.com\/index.php\/wp-json\/wp\/v2\/media?parent=197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}